{"id":12643,"date":"2023-11-07T14:28:20","date_gmt":"2023-11-07T13:28:20","guid":{"rendered":"https:\/\/javajan.es\/?p=12643"},"modified":"2024-09-06T12:41:48","modified_gmt":"2024-09-06T10:41:48","slug":"chatgpt","status":"publish","type":"post","link":"https:\/\/javajan.predev.eu\/es\/chatgpt\/","title":{"rendered":"ChatGPT"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12643\" class=\"elementor elementor-12643 elementor-94999\">\n\t\t\t\t\t\t<section class=\"default no-position elementor-section elementor-top-section elementor-element elementor-element-b79d5c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b79d5c0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e4c20f8\" data-id=\"7e4c20f8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-264e7ab elementor-widget elementor-widget-text-editor\" data-id=\"264e7ab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<blockquote><p><strong>\u00bfOs est\u00e1 cambiando la vida \u00bfHab\u00e9is experimentado con \u00e9l o ella? \u00bfAmigo o potencial enemigo?<\/strong><\/p><\/blockquote><p><em>Blade Runner, Matrix, Terminator, Yo robot, The 100, Humans, Severance, Osmosis<\/em>, son tantas las pel\u00edculas y series que nos han puesto la piel de gallina por culpa de esta tecnolog\u00eda que resulta normal tener dudas.<\/p><p><strong>Eh, un momento, que caras de desconcierto no? Sab\u00e9is que es, verdad?<\/strong><\/p><h5><strong>Caramba, que silencio m\u00e1s revelador, vamos a ponerle remedio pues:<\/strong><\/h5><ul><li><em>ChatGPT (o la versi\u00f3n de pago ChatGPT Plus) es una de las IA m\u00e1s capaces que han emergido en los \u00faltimos tiempos, siendo capaz de responder a cualquier cosa que le preguntes y de hacer muchas cosas que le solicites.<\/em><\/li><li><em>Es un sistema de chat basado en el modelo de lenguaje por Inteligencia Artificial GPT-3.5, desarrollado por la empresa OpenAI. Es un modelo con m\u00e1s de 175 millones de par\u00e1metros, y entrenado con grandes cantidades de texto para hacer tareas relacionadas con el lenguaje, desde la traducci\u00f3n hasta la generaci\u00f3n de texto.<\/em><\/li><li><em>Ha sido entrenada para mantener conversaciones con cualquier persona. Sus algoritmos tendr\u00edan que ser capaces de entender lo que le est\u00e9s preguntando con precisi\u00f3n, incluyendo adjetivos y variaciones que a\u00f1adas a tus frases, y de responderte de una manera coherente.<\/em><\/li><li><em>Lo m\u00e1s sorprendente de este chat por IA es que es capaz de darte unas respuestas muy acertadas y completas, incluso de varios p\u00e1rrafos. Adem\u00e1s, en estas respuestas es capaz de expresarse de manera natural y con informaci\u00f3n muy exacta, lo cual hace muy complicado distinguir que el texto ha sido generado por IA.<\/em><ul><li><em>Sin embargo, como cualquier modelo de IA, es posible que cometa errores en algunos puntos, por lo cual todo lo que nos escribe tampoco hay que tom\u00e1rselo como exacto.<\/em><\/li><\/ul><\/li><li><em>Adem\u00e1s de responder a la pregunta, esta IA tiene un sentido del contexto y reconoce todo lo que hab\u00e9is estado hablando hasta ahora, por lo cual si le haces alguna pregunta relacionada con una respuesta que te ha dado, sabr\u00e1 identificar si te refieres a esto sin tener que darle toda la explicaci\u00f3n.<\/em><\/li><\/ul><p><strong>Bien, ahora que ya est\u00e1is \u00abactualizados\u00bb, os proponemos que habl\u00e9is con Anna, el ChatGPT de <a href=\"https:\/\/javajan.cat\/\" target=\"_blank\" rel=\"noopener\">Javajan<\/a> para as\u00ed poder sacar vuestras propias conclusiones.<\/strong><\/p><ul><li>Eso s\u00ed, recordad que todo lo que escrib\u00eds queda registrado y puede ser revisado despu\u00e9s por nuestros t\u00e9cnicos para continuar entrenando a Anna (ChatGPT)<strong><em>. Por lo tanto, intentad no incluir informaci\u00f3n personal vuestra ni peticiones que sean potencialmente peligrosas o delictivas.<\/em><\/strong><\/li><li>Y recordad tambi\u00e9n que <strong>Anna<\/strong> est\u00e1 entrenada para hablar de nuestra empresa, seg\u00fan que le pregunt\u00e9is puede ser que las respuestas no tengan ning\u00fan sentido.<\/li><\/ul><p>Fuente: <a href=\"https:\/\/www.xataka.com\/basics\/chatgpt-que-como-usarlo-que-puedes-hacer-este-chat-inteligencia-artificial\">https:\/\/www.xataka.com\/basics\/chatgpt-que-como-usarlo-que-puedes-hacer-este-chat-inteligencia-artificial<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfOs est\u00e1 cambiando la vida \u00bfHab\u00e9is experimentado con \u00e9l o ella? \u00bfAmigo o potencial enemigo? Blade Runner, Matrix, Terminator, Yo robot, The 100, Humans, Severance, Osmosis, son tantas las pel\u00edculas y series que nos han puesto la piel de gallina por culpa de esta tecnolog\u00eda que resulta normal tener dudas. Eh, un momento, que caras&#8230;<\/p>\n","protected":false},"author":1,"featured_media":94532,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[186],"tags":[],"class_list":["post-12643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chat-gpt-open-ai-2"],"_links":{"self":[{"href":"https:\/\/javajan.predev.eu\/es\/wp-json\/wp\/v2\/posts\/12643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/javajan.predev.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/javajan.predev.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/javajan.predev.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/javajan.predev.eu\/es\/wp-json\/wp\/v2\/comments?post=12643"}],"version-history":[{"count":7,"href":"https:\/\/javajan.predev.eu\/es\/wp-json\/wp\/v2\/posts\/12643\/revisions"}],"predecessor-version":[{"id":105565,"href":"https:\/\/javajan.predev.eu\/es\/wp-json\/wp\/v2\/posts\/12643\/revisions\/105565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/javajan.predev.eu\/es\/wp-json\/wp\/v2\/media\/94532"}],"wp:attachment":[{"href":"https:\/\/javajan.predev.eu\/es\/wp-json\/wp\/v2\/media?parent=12643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/javajan.predev.eu\/es\/wp-json\/wp\/v2\/categories?post=12643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/javajan.predev.eu\/es\/wp-json\/wp\/v2\/tags?post=12643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}